{"id":11337,"date":"2019-10-10T12:24:49","date_gmt":"2019-10-10T10:24:49","guid":{"rendered":"http:\/\/limogesabc.com\/?p=11337"},"modified":"2019-10-10T12:27:31","modified_gmt":"2019-10-10T10:27:31","slug":"nf1-limoges-recoit-monaco-nombreuses-actions-et-animations-prevues","status":"publish","type":"post","link":"https:\/\/limogesabc.com\/index.php\/nf1-limoges-recoit-monaco-nombreuses-actions-et-animations-prevues\/","title":{"rendered":"NF1 Limoges re\u00e7oit Monaco, nombreuses actions et animations pr\u00e9vues."},"content":{"rendered":"<p><strong><span style=\"color: #003366;\">Apr\u00e8s deux victoires en deux matches, nous avons chut\u00e9 de deux petits points \u00e0 Feytiat. Deux points vraiment tr\u00e8s petits mais qui comptent. Le match fut beau, int\u00e9ressant, accroch\u00e9. C\u2019est ce que nous voulons retrouver samedi soir pour valider notre d\u00e9but de saison et calmer les ardeurs mon\u00e9gasques en prenant cette fois &#8230; les deux points ! <\/span>\u00a0<\/strong><\/p>\n<p><strong>Le match sera parrain\u00e9 par La Ligue contre le cancer<\/strong> dans le cadre de &#8220;<span style=\"color: #ff00ff;\">Octobre rose<\/span>&#8221; et \u00e0 cette occasion une collecte pour la Ligue sera disponible \u00e0 l&#8217;entr\u00e9e de la Salle Mu&#8217;. Jacques Lallet, Secr\u00e9taire g\u00e9n\u00e9ral de la Ligue contre le cancer &#8211; Comit\u00e9 Haute-Vienne &#8211; donnera le coup d&#8217;envoi de la rencontre. <em>Voir ci-dessous.<\/em><\/p>\n<p>Une animation sera en outre propos\u00e9e par<strong> La Pr\u00e9vention Routi\u00e8re<\/strong> <strong>&#8211; Comit\u00e9 87<\/strong> &#8211; en partenariat avec la MILDECA (Mission Interminist\u00e9rielle de Lutte contre les Drogues et les Conduites Addictives) sous la forme d&#8217;une sensibilisation visant \u00e0 r\u00e9duire les risques routiers li\u00e9s \u00e0 l\u2019alcoolisation festive et \u00e9v\u00e9nementielle ainsi qu\u2019\u00e0 l\u2019usage du cannabis. Cette animation, avec lunettes et parcours fictif, sera propos\u00e9e en ext\u00e9rieur.<\/p>\n<p>Enfin, dans le cadre de &#8220;<strong>Tous Arbitres<\/strong>&#8221; et des Journ\u00e9es de l&#8217;Arbitrage, une jeune joueuse du club &#8211; Nabintou &#8211; accompagnera les deux officiels pour une sorte de stage inside avec d\u00e9briefs sur les actions de la rencontre et sur la gestion du match. Nabintou s&#8217;inscrit cette ann\u00e9e \u00e0 notre Ecole d&#8217;Arbitrage labellis\u00e9e.<\/p>\n<p><span style=\"color: #ff00ff;\"><em><strong>Octobre Rose : la Ligue encourage toutes les femmes \u00e0 se faire d\u00e9pister \u2026 Le Comit\u00e9 d\u00e9partemental Haute-Vienne se mobilise<\/strong> <\/em><\/span><br \/>\n<span style=\"color: #ff00ff;\"><em>Face au cancer du sein, la meilleure arme : le d\u00e9pistage ! D\u00e9pist\u00e9 t\u00f4t, le cancer du sein est aujourd\u2019hui gu\u00e9rissable dans 90% des cas ! La Ligue contre le cancer entend plus que jamais poursuivre le combat pour faire de la pr\u00e9vention et du d\u00e9pistage des moyens efficaces pour lutter contre les cancers du sein ! C\u2019est avec la volont\u00e9 de sensibiliser le plus de femmes possibles et d\u2019encourager la participation au d\u00e9pistage que la Ligue est pr\u00e9sente dans diverses manifestations tout au long du mois d\u2019octobre. La Ligue soutient par ailleurs les activit\u00e9s et modes de vie permettant de r\u00e9duire le risque de cancer du sein, faciliter sa gu\u00e9rison et \u00e9viter sa r\u00e9cidive : arr\u00eat du tabac, r\u00e9duction de la consommation d\u2019alcool, alimentation \u00e9quilibr\u00e9e et vari\u00e9e et, surtout, la pratique d\u2019une activit\u00e9 physique r\u00e9guli\u00e8re.<\/em><\/span><\/p>\n<p><span style=\"color: #003366;\">Entr\u00e9e : 6 \u20ac \u00e0 partir de 19h. Lever de rideau en U18 ID vs Saint-L\u00e9onard\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s deux victoires en deux matches, nous avons chut\u00e9 de deux petits points \u00e0 Feytiat. Deux points vraiment tr\u00e8s petits mais qui comptent. Le match fut beau, int\u00e9ressant, accroch\u00e9. C\u2019est ce que nous voulons retrouver samedi soir pour valider notre d\u00e9but de saison et calmer les ardeurs mon\u00e9gasques en prenant cette fois &#8230; les deux&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/limogesabc.com\/index.php\/nf1-limoges-recoit-monaco-nombreuses-actions-et-animations-prevues\/\" class=\"excerpt-read-more\">Lire plus<\/a><\/p>\n","protected":false},"author":2,"featured_media":11338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-11337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/11337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/comments?post=11337"}],"version-history":[{"count":3,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/11337\/revisions"}],"predecessor-version":[{"id":11341,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/11337\/revisions\/11341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/media\/11338"}],"wp:attachment":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/media?parent=11337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/categories?post=11337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/tags?post=11337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}