{"id":18015,"date":"2023-01-29T20:50:04","date_gmt":"2023-01-29T19:50:04","guid":{"rendered":"http:\/\/limogesabc.com\/?p=18015"},"modified":"2023-01-29T20:59:32","modified_gmt":"2023-01-29T19:59:32","slug":"en-u18-elite-et-nf3-le-travail-de-formation-porte-ses-fruits","status":"publish","type":"post","link":"https:\/\/limogesabc.com\/index.php\/en-u18-elite-et-nf3-le-travail-de-formation-porte-ses-fruits\/","title":{"rendered":"En U18 Elite et NF3, le travail de formation porte ses fruits"},"content":{"rendered":"<p><span style=\"color: #003366;\">Nos deux \u00e9quipes de championnat de France jouaient ce dimanche Salle Mu\u2019. Deux \u00e9quipes \u00e0 domicile et deux victoires qui viennent agr\u00e9ablement compl\u00e9ter la victoire de l\u2019\u00e9quipe premi\u00e8re samedi soir \u00e0 Bordeaux. Un bon week-end et des positions fortes en haut des championnats. Nous avons demand\u00e9 aux deux coaches, <strong>Corentin Le Pan<\/strong> et <strong>Cl\u00e9ment Magnaval<\/strong>, de nous faire part de leurs analyses des matches. Et \u00e0 <strong>Christophe S\u00e9mavoine<\/strong>, Vice-Pr\u00e9sident en charge du Projet sportif, de nous livrer son sentiment sur les rencontres mais aussi sur le travail de formation au sein du club. <strong>Contributions et T\u00e9moignages.<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #800080;\"><strong>Les U18 Elite arrivent dans le trio de t\u00eate<\/strong><\/span><\/p>\n<p><span style=\"color: #993300;\"><strong>Christophe S\u00e9mavoine :<\/strong> <\/span>\u00ab\u00a0Nos U18 Elite rencontraient \u00e0 13h15 l&#8217;\u00e9quipe de l&#8217;AS Saint-Delphin. Le groupe de Corentin a abord\u00e9 le d\u00e9but du match avec beaucoup de concentration et d\u00e9termination, nous permettant d&#8217;\u00eatre devant de vingt points \u00e0 la mi-temps. L&#8217;\u00e9quipe a \u00e9t\u00e9 s\u00e9rieuse en seconde mi-temps et toutes les joueuses ont particip\u00e9 \u00e0 cette rencontre. La victoire (79-58) permet \u00e0 notre \u00e9quipe d&#8217;\u00eatre dans le trio de t\u00eate de cette seconde phase du groupe A. L&#8217;\u00e9quipe progresse, les filles et le staff sont motiv\u00e9s et d\u00e9termin\u00e9s, les b\u00e9n\u00e9voles autour de l&#8217;\u00e9quipe sont totalement investis et les r\u00e9sultats actuels sont une juste r\u00e9compense pour tout cet investissement. Nous devons \u00eatre ambitieux pour la suite du championnat ainsi que pour la Coupe de France.\u00a0\u00bb<\/p>\n<p><span style=\"color: #800080;\"><strong>Corentin Le Pan, coach :<\/strong> <\/span>\u00ab\u00a0C&#8217;\u00e9tait un match qu&#8217;il fallait gagner face \u00e0 une \u00e9quipe &#8220;promue&#8221; en 2\u00e8me phase de Groupe A, et les filles ont fait le job avec application. D&#8217;entr\u00e9e, elles ont pris le match en main, avec s\u00e9rieux et dans le respect des consignes. Les joueuses ont ma\u00eetris\u00e9 l&#8217;avance acquise en 1\u00e8re mi-temps pour d\u00e9rouler jusqu&#8217;au coup de sifflet final. Beau collectif !\u00a0\u00bb<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #800080;\"><strong>La NF3 conforte sa 5<sup>\u00e8me<\/sup> place<\/strong><\/span><\/p>\n<p><span style=\"color: #993300;\"><strong>Christophe S\u00e9mavoine :<\/strong> <\/span>\u00ab Notre \u00e9quipe NF3 affrontait ensuite, \u00e0 15h30, Les Herbiers Vend\u00e9e Basket, class\u00e9s \u00e0 la 6\u00e8me place, et qui nous avait battu lors du match aller. Nous souhaitions prendre notre revanche car nous avions \u00e9t\u00e9 absents de la premi\u00e8re mi-temps lors de ce premier match. Le message a \u00e9t\u00e9 pass\u00e9 par coach Cl\u00e9ment. Et ce fut chose faite. L&#8217;\u00e9quipe n&#8217;a rien l\u00e2ch\u00e9, elle a fait preuve de beaucoup de solidarit\u00e9, de combativit\u00e9 pour aller chercher cette victoire (64-56) qui nous permet ce soir d&#8217;\u00eatre seul 5\u00e8me du championnat. Cette \u00e9quipe est compos\u00e9e d&#8217;une grande majorit\u00e9 de joueuses issues de la formation Limoges ABC \u00e0 laquelle nous avons ajout\u00e9 des \u00e9l\u00e9ments importants. Nous sommes vraiment satisfaits du classement actuel mais, comme pour nos U18 Elite, nous devons \u00eatre ambitieux et avoir comme objectif les trois premi\u00e8res places. \u00bb<\/p>\n<p><span style=\"color: #800080;\"><strong>Cl\u00e9ment Magnaval, coach :<\/strong> <\/span>\u00ab Les filles \u00e9taient dans un \u00e9tat d\u2019esprit revanchard apr\u00e8s la d\u00e9faite du match aller. Elles ont fait preuve d\u2019une bonne coh\u00e9sion et ont men\u00e9 au score pendant trois quarts temps, l\u2019\u00e9cart montant jusqu\u2019\u00e0 une quinzaine de points. Les Herbiers ont propos\u00e9 une tr\u00e8s belle opposition et beaucoup de caract\u00e8re, nous obligeant \u00e0 rester s\u00e9rieux et impliqu\u00e9s jusqu\u2019\u00e0 la derni\u00e8re seconde. \u00bb<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #800080;\"><strong>&#8220;Le travail de formation porte ses fruits&#8221;<\/strong><\/span><\/p>\n<p><span style=\"color: #993300;\"><strong>Christophe S\u00e9mavoine\u00a0:<\/strong> <\/span>\u00ab\u00a0Le travail de formation mis en place depuis plusieurs ann\u00e9es au Limoges ABC porte ses fruits. Nos joueuses progressent, nos coachs progressent et c&#8217;est donc le Limoges ABC qui avance et qui est reconnu pour sa formation. Beaucoup de fiert\u00e9 d&#8217;\u00eatre dans ce projet et dans le club.\u00a0\u00bb<\/p>\n<p><a href=\"https:\/\/limogesabc.com\/index.php\/u18-elite-et-nf3-temoignages-sur-nos-deux-belles-victoires\/u18-elite-match-saint-delphin\/\" rel=\"attachment wp-att-18017\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-18017\" src=\"https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/01\/U18-ELITE-match-Saint-Delphin.jpg\" alt=\"\" width=\"2016\" height=\"1512\" srcset=\"https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/01\/U18-ELITE-match-Saint-Delphin.jpg 2016w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/01\/U18-ELITE-match-Saint-Delphin-300x225.jpg 300w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/01\/U18-ELITE-match-Saint-Delphin-1024x768.jpg 1024w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/01\/U18-ELITE-match-Saint-Delphin-150x113.jpg 150w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/01\/U18-ELITE-match-Saint-Delphin-768x576.jpg 768w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/01\/U18-ELITE-match-Saint-Delphin-1536x1152.jpg 1536w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/01\/U18-ELITE-match-Saint-Delphin-400x300.jpg 400w\" sizes=\"(max-width: 2016px) 100vw, 2016px\" \/><\/a><\/p>\n<h6>29 janvier 2023<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Nos deux \u00e9quipes de championnat de France jouaient ce dimanche Salle Mu\u2019. Deux \u00e9quipes \u00e0 domicile et deux victoires qui viennent agr\u00e9ablement compl\u00e9ter la victoire de l\u2019\u00e9quipe premi\u00e8re samedi soir \u00e0 Bordeaux. Un bon week-end et des positions fortes en haut des championnats. Nous avons demand\u00e9 aux deux coaches, Corentin Le Pan et Cl\u00e9ment Magnaval,&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/limogesabc.com\/index.php\/en-u18-elite-et-nf3-le-travail-de-formation-porte-ses-fruits\/\" class=\"excerpt-read-more\">Lire plus<\/a><\/p>\n","protected":false},"author":2,"featured_media":18016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[79,91],"tags":[],"class_list":["post-18015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-pole_formation"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/18015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/comments?post=18015"}],"version-history":[{"count":6,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/18015\/revisions"}],"predecessor-version":[{"id":18023,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/18015\/revisions\/18023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/media\/18016"}],"wp:attachment":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/media?parent=18015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/categories?post=18015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/tags?post=18015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}