{"id":19596,"date":"2023-09-08T16:02:26","date_gmt":"2023-09-08T14:02:26","guid":{"rendered":"http:\/\/limogesabc.com\/?p=19596"},"modified":"2023-09-08T17:56:29","modified_gmt":"2023-09-08T15:56:29","slug":"lancement-de-la-nouvelle-saison-du-csp-le-limoges-abc-aux-premieres-loges","status":"publish","type":"post","link":"https:\/\/limogesabc.com\/index.php\/lancement-de-la-nouvelle-saison-du-csp-le-limoges-abc-aux-premieres-loges\/","title":{"rendered":"Lancement de la nouvelle saison du CSP, le Limoges ABC aux premi\u00e8res loges !"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19596\" class=\"elementor elementor-19596\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41218ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41218ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b816740\" data-id=\"b816740\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15b96e5 elementor-widget elementor-widget-text-editor\" data-id=\"15b96e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 29-11-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p style=\"text-align: center;\">De gauche \u00e0 droite : Christophe SEMAVOINE (pr\u00e9sident par int\u00e9rim du Limoges ABC), Angiolina FORTE ( Directrice communication du CSP), Franck BUTTER (Vice-pr\u00e9sident du CSP), Celine FORTE (Actionnaire principale du CSP), Didier JAMOT (pr\u00e9sident du Limoges CSP) et Yannick FOURNIE (tr\u00e9sorier du Limoges ABC) <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d7d1302 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d7d1302\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c1a7df2\" data-id=\"6c1a7df2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1460b903 elementor-widget elementor-widget-text-editor\" data-id=\"1460b903\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><!-- wp:tadv\/classic-paragraph --><\/p>\n<p><span style=\"color: #000000;\">Le<\/span> <span style=\"color: #800000;\"><strong>Limoges ABC<\/strong><\/span> <span style=\"color: #000000;\">\u00e9tait pr\u00e9sent hier soir, \u00e0 l\u2019h\u00f4tel du d\u00e9partement \u00e0 l&#8217;occasion de la soir\u00e9e de lancement de la nouvelle saison du CSP.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dans un cadre chaleureux et convivial au sein des locaux du <\/span><span style=\"color: #003366;\">Conseil<\/span> <span style=\"color: #003366;\">d\u00e9partemental de la Haute-Vienne<\/span>, <span style=\"color: #000000;\">la soir\u00e9e fut dict\u00e9e par la pr\u00e9sentation de la <strong>nouvelle \u00e9quipe<\/strong> et des <strong>nouveaux maillots<\/strong> du club historique limougeaud.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le Limoges CSP et le Limoges ABC continuent d\u2019avancer &#8220;ENSEMBLE&#8221; et tout comme la saison derni\u00e8re, le logo symbolisant le rapprochement entre les deux clubs<\/span> <span style=\"color: #000000;\">figure sur les maillots de la saison 2023-2024.<\/span><\/p>\n<p><span style=\"color: #000000;\">R\u00e9alis\u00e9 par<strong> CRAFT Sportswear<\/strong>, \u00e9quipementier commun aux deux entit\u00e9s, notre rapprochement sera encore plus appuy\u00e9 avec les maillots de notre \u00e9quipe NF1.<\/span><\/p>\n<p><span style=\"color: #000000;\">Nous n&#8217;en dirons pas plus pour le moment&#8230; et nous vous laissons patienter avec cet indice jusqu&#8217;\u00e0 la pr\u00e9sentation de nos futurs maillots que nous r\u00e9aliserons tr\u00e8s prochainement ! <\/span><span data-testid=\"emoji\">\ud83d\ude09<\/span><\/p>\n<p><span style=\"color: #000000;\">La Team du Limoges ABC<\/span>\u00a0 <span data-testid=\"emoji\">\ud83d\udd35<\/span><span data-testid=\"emoji\">\ud83d\udd34<\/span><\/p>\n<p><!-- \/wp:tadv\/classic-paragraph --><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66bb4d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66bb4d9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-337c9ff\" data-id=\"337c9ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d81979d elementor-widget elementor-widget-image\" data-id=\"d81979d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 29-11-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-19603\" alt=\"\" srcset=\"https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp-150x150.jpg 150w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp-300x300.jpg 300w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp-1024x1024.jpg 1024w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp-768x768.jpg 768w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp-310x310.jpg 310w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp-60x60.jpg 60w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp-400x400.jpg 400w, https:\/\/limogesabc.com\/wp-content\/uploads\/2023\/09\/logo-commun-labc-csp.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>De gauche \u00e0 droite : Christophe SEMAVOINE (pr\u00e9sident par int\u00e9rim du Limoges ABC), Angiolina FORTE ( Directrice communication du CSP), Franck BUTTER (Vice-pr\u00e9sident du CSP), Celine FORTE (Actionnaire principale du CSP), Didier JAMOT (pr\u00e9sident du Limoges CSP) et Yannick FOURNIE (tr\u00e9sorier du Limoges ABC) Le Limoges ABC \u00e9tait pr\u00e9sent hier soir, \u00e0 l\u2019h\u00f4tel du d\u00e9partement&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/limogesabc.com\/index.php\/lancement-de-la-nouvelle-saison-du-csp-le-limoges-abc-aux-premieres-loges\/\" class=\"excerpt-read-more\">Lire plus<\/a><\/p>\n","protected":false},"author":2,"featured_media":19597,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-19596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/19596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/comments?post=19596"}],"version-history":[{"count":10,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/19596\/revisions"}],"predecessor-version":[{"id":19674,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/19596\/revisions\/19674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/media\/19597"}],"wp:attachment":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/media?parent=19596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/categories?post=19596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/tags?post=19596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}