{"id":4777,"date":"2018-02-04T14:51:50","date_gmt":"2018-02-04T13:51:50","guid":{"rendered":"http:\/\/limogesabc.com\/?p=4777"},"modified":"2018-02-04T14:51:50","modified_gmt":"2018-02-04T13:51:50","slug":"le-nouveau-comite-directeur-du-limoges-abc","status":"publish","type":"post","link":"https:\/\/limogesabc.com\/index.php\/le-nouveau-comite-directeur-du-limoges-abc\/","title":{"rendered":"Le nouveau Comit\u00e9 Directeur du Limoges ABC"},"content":{"rendered":"<p>L&#8217;Assembl\u00e9e G\u00e9n\u00e9rale du Limoges ABC <em>en Limousin<\/em> s&#8217;est r\u00e9unie mercredi 7 juin et a \u00e9lu <strong>le Comit\u00e9 Directeur du club<\/strong> compos\u00e9 ainsi qu&#8217;il suit : BENESTEVE Karine &#8211; COLOMBIER Christiane &#8211; FAURE Jean-Daniel &#8211; FOURNIE Yannick-Dominique &#8211; LEVEQUE Elisabeth &#8211; LIVERTOUT V\u00e9ronique &#8211; MANGIN Sybille &#8211; MEUNIER Val\u00e9rie &#8211; NARBONNE Pierre &#8211; ROBERT Jean-Paul &#8211; SEMAVOINE Christophe &#8211; SOULIERE Jean-Luc &#8211; THROMAS Arnaud &#8211; VAMPOUILLE Samuel.<\/p>\n<p>&nbsp;<\/p>\n<p>Le Comit\u00e9 Directeur s&#8217;est quant \u00e0 lui r\u00e9uni lundi 12 juin et a\u00a0organis\u00e9 les responsabilit\u00e9s de chacun dans le fonctionnement du club.<\/p>\n<p><strong>Huit membres ont \u00e9lus au Bureau :<\/strong><\/p>\n<p>Pr\u00e9sident : Jean-Paul ROBERT<\/p>\n<p>Secr\u00e9taire, Relations Ligue et Comit\u00e9 HV : Pierre NARBONNE<\/p>\n<p>Tr\u00e9sorier : Yannick-Dominique FOURNIE<\/p>\n<p>Communication et Responsable Equipe 1\u00e8re : Sybille MANGIN<\/p>\n<p>Responsable Administratif Centre d\u2019Entra\u00eenement : Jean-Daniel FAURE<\/p>\n<p>Commission Animation : Christiane COLOMBIER<\/p>\n<p>Co-coordonnateur Responsables d\u2019\u00e9quipes\u00a0: Arnaud THROMAS<\/p>\n<p>Ecole de Basket : Samuel VAMPOUILLE<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Responsabilit\u00e9s\u00a0au Comit\u00e9 Directeur<\/strong><\/p>\n<p>Co-coordonnateur Responsables d\u2019\u00e9quipes : V\u00e9ronique LIVERTOUT<\/p>\n<p>Relations Ville de Limoges\u00a0: Jean-Luc SOULIERE<\/p>\n<p>Ecole de Basket\u00a0: Karine BENESTEVE<\/p>\n<p>Mat\u00e9riels et Tenues des \u00e9quipes\u00a0: Elisabeth LEVEQUE et Val\u00e9rie MEUNIER<\/p>\n<p>Tournois et Ev\u00e9nementiels\u00a0: Christophe SEMAVOINE<\/p>\n<p>&nbsp;<\/p>\n<p>Le club est\u00a0donc pr\u00eat pour la\u00a0saison 2017-2018. Concernant le niveau d&#8217;engagement des \u00e9quipes, nous attendons des informations officielles de la FFBB qui\u00a0continue ces jours-ci les auditions des clubs de Championnat de France avant de communiquer sur les engagements 2017-2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Assembl\u00e9e G\u00e9n\u00e9rale du Limoges ABC en Limousin s&#8217;est r\u00e9unie mercredi 7 juin et a \u00e9lu le Comit\u00e9 Directeur du club compos\u00e9 ainsi qu&#8217;il suit : BENESTEVE Karine &#8211; COLOMBIER Christiane &#8211; FAURE Jean-Daniel &#8211; FOURNIE Yannick-Dominique &#8211; LEVEQUE Elisabeth &#8211; LIVERTOUT V\u00e9ronique &#8211; MANGIN Sybille &#8211; MEUNIER Val\u00e9rie &#8211; NARBONNE Pierre &#8211; ROBERT Jean-Paul &#8211;&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/limogesabc.com\/index.php\/le-nouveau-comite-directeur-du-limoges-abc\/\" class=\"excerpt-read-more\">Lire plus<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[81,94],"tags":[],"class_list":["post-4777","post","type-post","status-publish","format-standard","hentry","category-tout","category-club"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/4777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/comments?post=4777"}],"version-history":[{"count":1,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/4777\/revisions"}],"predecessor-version":[{"id":4778,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/posts\/4777\/revisions\/4778"}],"wp:attachment":[{"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/media?parent=4777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/categories?post=4777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limogesabc.com\/index.php\/wp-json\/wp\/v2\/tags?post=4777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}